{"id":1270,"date":"2012-03-15T09:56:35","date_gmt":"2012-03-15T08:56:35","guid":{"rendered":"https:\/\/apartamentoselvalledor.com\/la-parra\/"},"modified":"2024-03-03T19:14:05","modified_gmt":"2024-03-03T18:14:05","slug":"la-parra","status":"publish","type":"page","link":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/","title":{"rendered":"La Parra"},"content":{"rendered":"\n<p class=\"has-text-align-center\"><img loading=\"lazy\" decoding=\"async\" title=\"La Parra\" width=\"920\" height=\"360\" class=\"alignnone size-full wp-image-58\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg\" alt=\"\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1-300x117.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1-500x195.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg 920w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/p>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>Apartment <strong>LA PARRA<\/strong>, \u201c<em>The Vine<\/em>\u201d, is located on the main floor of the old house and it is name after the vines that were common in all of the villages in the area.<\/p>\n\n\n\n<p>\u201cParras\u201d are wooden structures similar to a pergola, in which vines grew, contributing substantially to shade the paths, which were a usual meeting point to chat between tasks, and get a shelter on the sunny days. It is due to the microclimate of the <strong>Valledor<\/strong> that vines grew here.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p><strong>LA PARRA<\/strong> is ideal for 4 people, with a double room with a bed of 1.35 cm and another one with two attached 90 cm beds, a large bathroom, living room with fireplace and kitchen. Its views will let you enjoy the most immediate landscapes and the stunning sunrises.<\/p>\n\n\n\n<p>The apartment is equipped with everything you need for a quality stay: dishwasher, oven, microwave, fridge with fridge and kitchenware for 6 people.<\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"mai-gallery has-columns\" id=\"mai-gallery-1\" style=\"--columns-xs:1 \/ 2;--columns-sm:1 \/ 2;--columns-md:1 \/ 3;--columns-lg:1 \/ 5;--flex-xs:0 0 var(--flex-basis);--flex-sm:0 0 var(--flex-basis);--flex-md:0 0 var(--flex-basis);--flex-lg:0 0 var(--flex-basis);--column-gap:var(--spacing-xl);--row-gap:var(--spacing-xl);--align-columns:start;--align-columns-vertical:initial;--image-filter:var(--drop-shadow);\"><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1600px) 100vw, 1600px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1.jpg 1600w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"La Parra 1\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-1.jpg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1600px) 100vw, 1600px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2.jpg 1600w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"La Parra 2\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-2.jpg 1600w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"La Parra 3\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-3.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"La Parra 4\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-4.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-1024x769.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"La Parra 5\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5-1024x769.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra-5.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>Apartment LA PARRA, \u201cThe Vine\u201d, is located on the main floor of the old house and it is name after the vines that were common in all of the villages in the area. \u201cParras\u201d are wooden structures similar to a pergola, in which vines grew, contributing substantially to shade the paths, which were a usual &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1080,"parent":1295,"menu_order":2,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"mai_display":[11,18],"class_list":{"1":"page","2":"type-page","6":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La Parra - Apartamentos El Valledor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La Parra - Apartamentos El Valledor\" \/>\n<meta property=\"og:description\" content=\"Apartment LA PARRA, \u201cThe Vine\u201d, is located on the main floor of the old house and it is name after the vines that were common in all of the villages in the area. \u201cParras\u201d are wooden structures similar to a pergola, in which vines grew, contributing substantially to shade the paths, which were a usual &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos El Valledor\" \/>\n<meta property=\"article:modified_time\" content=\"2024-03-03T18:14:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"920\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/\",\"name\":\"La Parra - Apartamentos El Valledor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/La-Parra1.jpg\",\"datePublished\":\"2012-03-15T08:56:35+00:00\",\"dateModified\":\"2024-03-03T18:14:05+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/La-Parra1.jpg\",\"contentUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/La-Parra1.jpg\",\"width\":\"920\",\"height\":\"360\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/la-parra\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Cotagge\",\"item\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-cotagge\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"La Parra\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#website\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/\",\"name\":\"Apartamentos El Valledor\",\"description\":\"Apartamentos Rurales en el Valle del Silencio\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#organization\",\"name\":\"Apartamentos El Valledor\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/logo_Valledor.png\",\"contentUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/logo_Valledor.png\",\"width\":175,\"height\":100,\"caption\":\"Apartamentos El Valledor\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La Parra - Apartamentos El Valledor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/","og_locale":"en_US","og_type":"article","og_title":"La Parra - Apartamentos El Valledor","og_description":"Apartment LA PARRA, \u201cThe Vine\u201d, is located on the main floor of the old house and it is name after the vines that were common in all of the villages in the area. \u201cParras\u201d are wooden structures similar to a pergola, in which vines grew, contributing substantially to shade the paths, which were a usual &hellip;","og_url":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/","og_site_name":"Apartamentos El Valledor","article_modified_time":"2024-03-03T18:14:05+00:00","og_image":[{"width":920,"height":360,"url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg","type":"image\/jpeg"}],"twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/","url":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/","name":"La Parra - Apartamentos El Valledor","isPartOf":{"@id":"https:\/\/apartamentoselvalledor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/#primaryimage"},"image":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg","datePublished":"2012-03-15T08:56:35+00:00","dateModified":"2024-03-03T18:14:05+00:00","breadcrumb":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/#primaryimage","url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg","contentUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/La-Parra1.jpg","width":"920","height":"360"},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/la-parra\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/apartamentoselvalledor.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"The Cotagge","item":"https:\/\/apartamentoselvalledor.com\/en\/the-cotagge\/"},{"@type":"ListItem","position":3,"name":"La Parra"}]},{"@type":"WebSite","@id":"https:\/\/apartamentoselvalledor.com\/#website","url":"https:\/\/apartamentoselvalledor.com\/","name":"Apartamentos El Valledor","description":"Apartamentos Rurales en el Valle del Silencio","publisher":{"@id":"https:\/\/apartamentoselvalledor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentoselvalledor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/apartamentoselvalledor.com\/#organization","name":"Apartamentos El Valledor","url":"https:\/\/apartamentoselvalledor.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/logo\/image\/","url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/logo_Valledor.png","contentUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/logo_Valledor.png","width":175,"height":100,"caption":"Apartamentos El Valledor"},"image":{"@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/logo\/image\/"}}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/pages\/1270","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/comments?post=1270"}],"version-history":[{"count":5,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/pages\/1270\/revisions"}],"predecessor-version":[{"id":1353,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/pages\/1270\/revisions\/1353"}],"up":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/pages\/1295"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/media\/1080"}],"wp:attachment":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/media?parent=1270"}],"wp:term":[{"taxonomy":"mai_display","embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/mai_display?post=1270"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}