{"id":1518,"date":"2020-09-05T14:57:58","date_gmt":"2020-09-05T13:57:58","guid":{"rendered":"https:\/\/apartamentoselvalledor.com\/the-valledor\/"},"modified":"2024-05-23T08:55:52","modified_gmt":"2024-05-23T07:55:52","slug":"the-valledor","status":"publish","type":"post","link":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/","title":{"rendered":"The Valledor"},"content":{"rendered":"<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno.jpg\"><img loading=\"lazy\" decoding=\"async\" width=\"920\" height=\"360\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno.jpg\" alt=\"\" class=\"wp-image-188\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno-300x117.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno-500x195.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno.jpg 920w\" sizes=\"auto, (max-width: 920px) 100vw, 920px\" \/><\/a><\/figure><\/div>\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-9d6595d7 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>The oldest evidence of life in the area takes us back to the Bronze Age, and walking along the peaks you will be able to find the remains of burials of the ancient times. Several forts testify important populations of pre-Roman era, and although most of them are unexcavated and only one is suitable for the visit, the hillfort of <strong>San Chuis<\/strong> located in the town of San Martin de Beduledo.<\/p>\n\n\n\n<p>But what has really left its mark and has give the valley its name was the presence of the Romans, attracted by the precious gold. They moved unimaginable amounts of land through \u201c<em>ruina<\/em> <em>montium<\/em>\u201d system whose consequences are still visible today, hence the name of <strong>Gold Valley<\/strong> or \u201c<strong>Territorio d\u2019Or<\/strong>\u201d as it appears in the oldest documents. The legend tells that the Romans left hidden treasures, including a golden ox, in their hurried flight.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>In the most recent Valledor history, which has been awarded the nickname <strong>Valley of Silence,<\/strong>after the silence that has prevailed during the second half of the last century, while its former inhabitants left in search of a better life and because of the geographic isolation of the area. This isolation was exacerbated by the construction of the <strong>dam of Salime<\/strong>, impressive civil engineering, (early 50\u2019s) marked the final abandonment of such beautiful places which are without any doubt one of our highlights.<\/p>\n\n\n\n<p>Visiting <strong>THE VALLEDOR<\/strong> you become part of it, its full of wisdom peasantry, its archaic, almost abandoned villages where it is easy to imagine how life was used to be like, and a priceless ethnographic heritage (cortines, water mills, sweatshops , fonts, granaries and breadboards(raised granaries) with own decorative style, etc). Definitely getting lost in the Valledor means discovering how much the silence has to tell you.<\/p>\n<\/div>\n<\/div>\n\n<div style=\"height:50px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<div class=\"mai-gallery has-columns\" id=\"mai-gallery-1\" style=\"--columns-xs:1 \/ 2;--columns-sm:1 \/ 2;--columns-md:1 \/ 3;--columns-lg:1 \/ 5;--flex-xs:0 0 var(--flex-basis);--flex-sm:0 0 var(--flex-basis);--flex-md:0 0 var(--flex-basis);--flex-lg:0 0 var(--flex-basis);--column-gap:var(--spacing-md);--row-gap:var(--spacing-md);--align-columns:start;--align-columns-vertical:initial;--image-filter:var(--drop-shadow);\"><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-500x333.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-1024x683.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"267\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 25\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-500x333.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25-1024x683.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-25.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 24\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-24.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1024px) 100vw, 1024px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20.jpg 1024w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_20\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_20.jpg 1024w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-300x235.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-300x235.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-500x391.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-1024x802.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"383\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 22\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-300x235.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-500x391.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22-1024x802.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-22.jpg 2048w\" sizes=\"auto, (max-width: 383px) 100vw, 383px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 21\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-21.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-300x224.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-300x224.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-500x374.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-1024x767.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 20\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-300x224.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-500x374.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20-1024x767.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-20.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 9\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-9.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 10\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-10.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 11\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-11.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 12\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-12.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13.jpg 2560w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 13\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-13.jpg 2560w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14.jpg 2560w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 14\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-14.jpg 2560w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 16\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-16.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 17\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-17.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 18\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-18.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 8\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-8.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7.jpg 2560w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 7\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-7.jpg 2560w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-300x224.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-300x224.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6.jpg 2272w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 6\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-300x224.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-6.jpg 2272w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5.jpg 2560w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 5\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5-1024x684.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-5.jpg 2560w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 4\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-4.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 2\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-2.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-300x200.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"268\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 1\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-300x200.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-500x334.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1-1024x685.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-1.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 15\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-500x375.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-15.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1200x900.jpg 1200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1536x1152.jpg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_22\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1200x900.jpg 1200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22-1536x1152.jpg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_22.jpg 2048w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-300x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-80x80.jpg 80w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-150x150.jpg 150w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-300x300.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-400x400.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-768x768.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-800x800.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-1024x1024.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-1200x1200.jpg 1200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-1536x1536.jpg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_23\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_23-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-252x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1718px) 100vw, 1718px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-252x300.jpg 252w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-768x915.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-859x1024.jpg 859w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-1289x1536.jpg 1289w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-1718x2048.jpg 1718w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_24\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_24-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-300x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-80x80.jpg 80w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-150x150.jpg 150w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-300x300.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-400x400.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-768x768.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-800x800.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-1024x1024.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-1200x1200.jpg 1200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-1536x1536.jpg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_25\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_25-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_26-225x300.jpeg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 768px) 100vw, 768px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_26-225x300.jpeg 225w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_26.jpeg 768w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_26-400x300.jpeg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_26\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-300x169.jpeg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-300x169.jpeg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-768x432.jpeg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-1024x576.jpeg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-1536x864.jpeg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2.jpeg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-400x300.jpeg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_2\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-400x300.jpeg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-800x600.jpeg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_2-1200x900.jpeg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_3-300x169.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_3-300x169.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_3-768x432.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_3.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_3-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_3\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_4\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_4.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_5-300x169.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_5-300x169.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_5-768x432.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_5.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_5-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_5\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_6\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_6.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_7\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_7.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_8\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_8.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 960px) 100vw, 960px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9.jpg 960w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_9\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_9.jpg 960w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_10\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_10.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_11\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_11.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_12\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_12.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_13\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_13.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_14\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_14.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_15\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_15.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-300x209.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-300x209.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-768x535.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-1024x714.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_16\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_16-800x600.jpg 800w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_17\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_17.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-300x225.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1080px) 100vw, 1080px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18.jpg 1080w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_18\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-300x225.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-768x576.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18-1024x768.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_18.jpg 1080w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-300x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 2048px) 100vw, 2048px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-80x80.jpg 80w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-150x150.jpg 150w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-300x300.jpg 300w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-400x400.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-768x768.jpg 768w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-800x800.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-1024x1024.jpg 1024w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-1200x1200.jpg 1200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-1536x1536.jpg 1536w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19.jpg 2048w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"400\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-400x300.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"el_valledor_19\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-400x300.jpg 400w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-800x600.jpg 800w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/el_valledor_19-1200x900.jpg 1200w\" sizes=\"auto, (max-width: 400px) 100vw, 400px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-200x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1370px) 100vw, 1370px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-685x1024.jpg 685w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19.jpg 1370w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 19\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19-685x1024.jpg 685w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-19.jpg 1370w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-200x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 1370px) 100vw, 1370px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-685x1024.jpg 685w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23.jpg 1370w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 23\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23-685x1024.jpg 685w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-23.jpg 1370w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/figure><figure class=\"mai-gallery-item is-column\"><a class=\"mai-gallery-image-link mai-gallery-lightbox\" href=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3-200x300.jpg\" data-gallery=\"mai-gallery-1\" data-sizes=\"(max-width: 642px) 100vw, 642px\" data-srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3.jpg 642w\" data-glightbox=\"description:\"><img loading=\"lazy\" decoding=\"async\" width=\"201\" height=\"300\" src=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3.jpg\" class=\"mai-gallery-image size-landscape-sm\" alt=\"\" title=\"El Valledor 3\" srcset=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3-200x300.jpg 200w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3-500x747.jpg 500w, https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Valledor-3.jpg 642w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/figure><\/div>","protected":false},"excerpt":{"rendered":"<p>The oldest evidence of life in the area takes us back to the Bronze Age, and walking along the peaks you will be able to find the remains of burials of the ancient times. Several forts testify important populations of pre-Roman era, and although most of them are unexcavated and only one is suitable for &hellip;<\/p>\n","protected":false},"author":1,"featured_media":1522,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"_genesis_hide_title":false,"_genesis_hide_breadcrumbs":false,"_genesis_hide_singular_image":false,"_genesis_hide_footer_widgets":false,"_genesis_custom_body_class":"","_genesis_custom_post_class":"","_genesis_layout":"","footnotes":""},"categories":[23],"tags":[],"mai_display":[],"class_list":{"2":"type-post","7":"category-what-to-see","8":"entry"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>The Valledor - Apartamentos El Valledor<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"The Valledor - Apartamentos El Valledor\" \/>\n<meta property=\"og:description\" content=\"The oldest evidence of life in the area takes us back to the Bronze Age, and walking along the peaks you will be able to find the remains of burials of the ancient times. Several forts testify important populations of pre-Roman era, and although most of them are unexcavated and only one is suitable for &hellip;\" \/>\n<meta property=\"og:url\" content=\"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/\" \/>\n<meta property=\"og:site_name\" content=\"Apartamentos El Valledor\" \/>\n<meta property=\"article:published_time\" content=\"2020-09-05T13:57:58+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2024-05-23T07:55:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"360\" \/>\n\t<meta property=\"og:image:height\" content=\"360\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"admin\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"admin\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/\"},\"author\":{\"name\":\"admin\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/person\\\/bcb44957e0a77fd81841cb3f7baef2f7\"},\"headline\":\"The Valledor\",\"datePublished\":\"2020-09-05T13:57:58+00:00\",\"dateModified\":\"2024-05-23T07:55:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/\"},\"wordCount\":298,\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/El-Entorno_featured_400-e1709507547138.jpg\",\"articleSection\":[\"What to see?\"],\"inLanguage\":\"en-US\"},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/\",\"name\":\"The Valledor - Apartamentos El Valledor\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/El-Entorno_featured_400-e1709507547138.jpg\",\"datePublished\":\"2020-09-05T13:57:58+00:00\",\"dateModified\":\"2024-05-23T07:55:52+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#primaryimage\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/El-Entorno_featured_400-e1709507547138.jpg\",\"contentUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/El-Entorno_featured_400-e1709507547138.jpg\",\"width\":360,\"height\":360},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/the-valledor\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/home\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"The Valledor\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#website\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/\",\"name\":\"Apartamentos El Valledor\",\"description\":\"Apartamentos Rurales en el Valle del Silencio\",\"publisher\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#organization\",\"name\":\"Apartamentos El Valledor\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/logo_Valledor.png\",\"contentUrl\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/wp-content\\\/uploads\\\/logo_Valledor.png\",\"width\":175,\"height\":100,\"caption\":\"Apartamentos El Valledor\"},\"image\":{\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/#\\\/schema\\\/person\\\/bcb44957e0a77fd81841cb3f7baef2f7\",\"name\":\"admin\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g\",\"caption\":\"admin\"},\"url\":\"https:\\\/\\\/apartamentoselvalledor.com\\\/en\\\/author\\\/admin\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"The Valledor - Apartamentos El Valledor","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/","og_locale":"en_US","og_type":"article","og_title":"The Valledor - Apartamentos El Valledor","og_description":"The oldest evidence of life in the area takes us back to the Bronze Age, and walking along the peaks you will be able to find the remains of burials of the ancient times. Several forts testify important populations of pre-Roman era, and although most of them are unexcavated and only one is suitable for &hellip;","og_url":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/","og_site_name":"Apartamentos El Valledor","article_published_time":"2020-09-05T13:57:58+00:00","article_modified_time":"2024-05-23T07:55:52+00:00","og_image":[{"width":360,"height":360,"url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg","type":"image\/jpeg"}],"author":"admin","twitter_misc":{"Written by":"admin","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#article","isPartOf":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/"},"author":{"name":"admin","@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/person\/bcb44957e0a77fd81841cb3f7baef2f7"},"headline":"The Valledor","datePublished":"2020-09-05T13:57:58+00:00","dateModified":"2024-05-23T07:55:52+00:00","mainEntityOfPage":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/"},"wordCount":298,"publisher":{"@id":"https:\/\/apartamentoselvalledor.com\/#organization"},"image":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg","articleSection":["What to see?"],"inLanguage":"en-US"},{"@type":"WebPage","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/","url":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/","name":"The Valledor - Apartamentos El Valledor","isPartOf":{"@id":"https:\/\/apartamentoselvalledor.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#primaryimage"},"image":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#primaryimage"},"thumbnailUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg","datePublished":"2020-09-05T13:57:58+00:00","dateModified":"2024-05-23T07:55:52+00:00","breadcrumb":{"@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#primaryimage","url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg","contentUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/El-Entorno_featured_400-e1709507547138.jpg","width":360,"height":360},{"@type":"BreadcrumbList","@id":"https:\/\/apartamentoselvalledor.com\/en\/the-valledor\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/apartamentoselvalledor.com\/en\/home\/"},{"@type":"ListItem","position":2,"name":"The Valledor"}]},{"@type":"WebSite","@id":"https:\/\/apartamentoselvalledor.com\/#website","url":"https:\/\/apartamentoselvalledor.com\/","name":"Apartamentos El Valledor","description":"Apartamentos Rurales en el Valle del Silencio","publisher":{"@id":"https:\/\/apartamentoselvalledor.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/apartamentoselvalledor.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/apartamentoselvalledor.com\/#organization","name":"Apartamentos El Valledor","url":"https:\/\/apartamentoselvalledor.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/logo\/image\/","url":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/logo_Valledor.png","contentUrl":"https:\/\/apartamentoselvalledor.com\/wp-content\/uploads\/logo_Valledor.png","width":175,"height":100,"caption":"Apartamentos El Valledor"},"image":{"@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/logo\/image\/"}},{"@type":"Person","@id":"https:\/\/apartamentoselvalledor.com\/#\/schema\/person\/bcb44957e0a77fd81841cb3f7baef2f7","name":"admin","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/410a420dea7dd4d8d4ba0ca2b9cf81d186a26bf9cebd73532bbd66d78f2f3821?s=96&d=mm&r=g","caption":"admin"},"url":"https:\/\/apartamentoselvalledor.com\/en\/author\/admin\/"}]}},"acf":[],"_links":{"self":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/posts\/1518","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/comments?post=1518"}],"version-history":[{"count":6,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/posts\/1518\/revisions"}],"predecessor-version":[{"id":1801,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/posts\/1518\/revisions\/1801"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/media\/1522"}],"wp:attachment":[{"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/media?parent=1518"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/categories?post=1518"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/tags?post=1518"},{"taxonomy":"mai_display","embeddable":true,"href":"https:\/\/apartamentoselvalledor.com\/en\/wp-json\/wp\/v2\/mai_display?post=1518"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}